{"id":11653,"date":"2022-03-18T12:33:00","date_gmt":"2022-03-18T11:33:00","guid":{"rendered":"https:\/\/www.tornosabogados.com\/?p=11653"},"modified":"2023-07-03T13:46:07","modified_gmt":"2023-07-03T11:46:07","slug":"tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners","status":"publish","type":"post","link":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/","title":{"rendered":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners"},"content":{"rendered":"<p style=\"text-align: justify;\">Tornos Abogados ha sido reconocida como <em>\u201cleading firm\u201d<\/em> en la Gu\u00eda Europea 2022 de <a href=\"https:\/\/www.linkedin.com\/authwall?trk=bf&amp;trkInfo=AQF2DXC0OblSrwAAAX-cyWZY2Vm1GVmhXkE2PV_CxL03f-yqDjRm7fBocwxS-qn3YeF2n03mnNsLKD4sDQVcoQolECSdC8Y5NbqjGAEwl026Pg5cG00BGyTzyOB5VDvgj4ncds0=&amp;originalReferer=&amp;sessionRedirect=https%3A%2F%2Fwww.linkedin.com%2Fcompany%2Fchambers-and-partners%2F\" rel=\"nofollow\"><em>Chambers and Partners<\/em><\/a>.<\/p>\n<p style=\"text-align: justify;\"><em>Chambers &amp; Partners<\/em> es el directorio internacional m\u00e1s prestigioso del sector legal, y selecciona a los letrados m\u00e1s relevantes del panorama nacional en cada una de las pr\u00e1cticas m\u00e1s destacadas en el derecho de los negocios. Nuestra firma ha sido destacada en las \u00e1reas de Derecho P\u00fablico y Medio Ambiente.<\/p>\n<p style=\"text-align: justify;\">Felicitamos a nuestros abogados Joaquin Tornos y Joan Perdig\u00f3 por aparecer reconocidos entre los mejores dentro de su especialidad.<\/p>\n<p style=\"text-align: justify;\">Por supuesto queremos agradecer a nuestros clientes la confianza que han demostrado en nuestros servicios de asesoramiento. Y no queremos dejar de reconocer el esfuerzo de todo el equipo de Tornos Abogados, puesto que sin su esfuerzo y su excelente trabajo, todo esto no habr\u00eda sido posible.<\/p>\n<p style=\"text-align: justify;\">Link al perfil de Tornos Abogados <a href=\"https:\/\/chambers.com\/law-firm\/tornos-abogados-slp-europe-7:120923\" target=\"_blank\" rel=\"noopener noreferrer\">https:\/\/chambers.com\/law-firm\/tornos-abogados-slp-europe-7:120923<\/a><\/p>\n<p>&nbsp;<\/p>\n<p><a href=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1.jpg\" rel=\"nofollow\"><img decoding=\"async\" loading=\"lazy\" class=\"size-full wp-image-13121 aligncenter\" src=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1.jpg\" alt=\"\" width=\"940\" height=\"788\" srcset=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1.jpg 940w, https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1-300x251.jpg 300w, https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1-768x644.jpg 768w\" sizes=\"(max-width: 940px) 100vw, 940px\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tornos Abogados ha sido reconocida como \u201cleading firm\u201d en la Gu\u00eda Europea 2022 de Chambers and Partners. Chambers &amp; Partners es el directorio internacional m\u00e1s prestigioso del sector legal, y selecciona a los letrados m\u00e1s relevantes del panorama nacional en cada una de las pr\u00e1cticas m\u00e1s destacadas en el derecho de los negocios. Nuestra firma [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"boletin":[],"articulo-lcsp":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos\" \/>\n<meta property=\"og:description\" content=\"Tornos Abogados ha sido reconocida como \u201cleading firm\u201d en la Gu\u00eda Europea 2022 de Chambers and Partners. Chambers &amp; Partners es el directorio internacional m\u00e1s prestigioso del sector legal, y selecciona a los letrados m\u00e1s relevantes del panorama nacional en cada una de las pr\u00e1cticas m\u00e1s destacadas en el derecho de los negocios. Nuestra firma [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornos\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-18T11:33:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-03T11:46:07+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1.jpg\" \/>\n<meta name=\"author\" content=\"Tornos Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tornos Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\"},\"author\":{\"name\":\"Tornos Abogados\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\"},\"headline\":\"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners\",\"datePublished\":\"2022-03-18T11:33:00+00:00\",\"dateModified\":\"2023-07-03T11:46:07+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\"},\"wordCount\":167,\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\"},\"articleSection\":[\"Noticias y Cursos\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\",\"name\":\"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#website\"},\"datePublished\":\"2022-03-18T11:33:00+00:00\",\"dateModified\":\"2023-07-03T11:46:07+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tornosabogados.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#website\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/\",\"name\":\"Tornos Abogados\",\"description\":\"Referentes en derecho administrativo\",\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tornosabogados.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\",\"name\":\"Tornos Abogados\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"contentUrl\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"width\":451,\"height\":194,\"caption\":\"Tornos Abogados\"},\"image\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\",\"name\":\"Tornos Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"caption\":\"Tornos Abogados\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/","og_locale":"ca_ES","og_type":"article","og_title":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos","og_description":"Tornos Abogados ha sido reconocida como \u201cleading firm\u201d en la Gu\u00eda Europea 2022 de Chambers and Partners. Chambers &amp; Partners es el directorio internacional m\u00e1s prestigioso del sector legal, y selecciona a los letrados m\u00e1s relevantes del panorama nacional en cada una de las pr\u00e1cticas m\u00e1s destacadas en el derecho de los negocios. Nuestra firma [&hellip;]","og_url":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/","og_site_name":"Tornos","article_published_time":"2022-03-18T11:33:00+00:00","article_modified_time":"2023-07-03T11:46:07+00:00","og_image":[{"url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2022\/03\/Chambers-Linkedin-1-1.jpg"}],"author":"Tornos Abogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tornos Abogados","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#article","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/"},"author":{"name":"Tornos Abogados","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97"},"headline":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners","datePublished":"2022-03-18T11:33:00+00:00","dateModified":"2023-07-03T11:46:07+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/"},"wordCount":167,"publisher":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#organization"},"articleSection":["Noticias y Cursos"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/","url":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/","name":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners - Tornos","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#website"},"datePublished":"2022-03-18T11:33:00+00:00","dateModified":"2023-07-03T11:46:07+00:00","breadcrumb":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-ha-sido-reconocido-un-ano-mas-por-el-directorio-chambers-and-partners\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tornosabogados.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Tornos Abogados ha sido reconocido un a\u00f1o m\u00e1s por el directorio Chambers and Partners"}]},{"@type":"WebSite","@id":"https:\/\/www.tornosabogados.com\/ca\/#website","url":"https:\/\/www.tornosabogados.com\/ca\/","name":"Tornos Abogados","description":"Referentes en derecho administrativo","publisher":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornosabogados.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/www.tornosabogados.com\/ca\/#organization","name":"Tornos Abogados","url":"https:\/\/www.tornosabogados.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","contentUrl":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","width":451,"height":194,"caption":"Tornos Abogados"},"image":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97","name":"Tornos Abogados","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","caption":"Tornos Abogados"}}]}},"_links":{"self":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/11653"}],"collection":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/comments?post=11653"}],"version-history":[{"count":5,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/11653\/revisions"}],"predecessor-version":[{"id":13126,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/11653\/revisions\/13126"}],"wp:attachment":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/media?parent=11653"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/categories?post=11653"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/tags?post=11653"},{"taxonomy":"boletin","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/boletin?post=11653"},{"taxonomy":"articulo-lcsp","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/articulo-lcsp?post=11653"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}