{"id":12735,"date":"2023-03-17T11:46:53","date_gmt":"2023-03-17T10:46:53","guid":{"rendered":"https:\/\/www.tornosabogados.com\/?p=12735"},"modified":"2023-03-17T11:53:17","modified_gmt":"2023-03-17T10:53:17","slug":"tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna","status":"publish","type":"post","link":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/","title":{"rendered":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a"},"content":{"rendered":"<p>Antonio Sala Cantarell, Socio de Tornos Abogados y Tom\u00e1s Cano Campos, Consejero Acad\u00e9mico de Tornos Abogados realizar\u00e1n el curso &#8220;<em>El incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos: \u00bfIus variandi o riesgo imprevisible? \u00daltimas novedades y cuestiones pr\u00e1cticas m\u00e1s relevantes<\/em>&#8220;.<\/p>\n<p>Este curso tiene por objetivo analizar el alcance del riesgo de ventura que asume el contratista en todo el sector p\u00fablico y la necesidad de respetar el equilibrio econ\u00f3mico en todos los contratos p\u00fablicos, as\u00ed como analizar la posibilidad de utilizar el ius variandi para modificar el precio y la compensaci\u00f3n por riesgo imprevisible.<\/p>\n<p><strong>El curso se realizar\u00e1 en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a \u00b7 Jueves 23 de marzo a las 12h.<\/strong><\/p>\n<p><em>La inscripci\u00f3n est\u00e1 abierta en exclusiva para los socios de la C\u00e1mara de Contratistas de Obras de Catalunya<\/em><\/p>\n<p><a href=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas.jpg\" rel=\"nofollow\"><img decoding=\"async\" loading=\"lazy\" class=\"wp-image-12742 aligncenter\" src=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas.jpg\" alt=\"\" width=\"857\" height=\"560\" srcset=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas.jpg 1244w, https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas-300x196.jpg 300w, https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas-1024x669.jpg 1024w, https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas-768x502.jpg 768w\" sizes=\"(max-width: 857px) 100vw, 857px\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Antonio Sala Cantarell, Socio de Tornos Abogados y Tom\u00e1s Cano Campos, Consejero Acad\u00e9mico de Tornos Abogados realizar\u00e1n el curso &#8220;El incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos: \u00bfIus variandi o riesgo imprevisible? \u00daltimas novedades y cuestiones pr\u00e1cticas m\u00e1s relevantes&#8220;. Este curso tiene por objetivo analizar el alcance del riesgo de ventura [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[1],"tags":[],"boletin":[],"articulo-lcsp":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos\" \/>\n<meta property=\"og:description\" content=\"Antonio Sala Cantarell, Socio de Tornos Abogados y Tom\u00e1s Cano Campos, Consejero Acad\u00e9mico de Tornos Abogados realizar\u00e1n el curso &#8220;El incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos: \u00bfIus variandi o riesgo imprevisible? \u00daltimas novedades y cuestiones pr\u00e1cticas m\u00e1s relevantes&#8220;. Este curso tiene por objetivo analizar el alcance del riesgo de ventura [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornos\" \/>\n<meta property=\"article:published_time\" content=\"2023-03-17T10:46:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2023-03-17T10:53:17+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas.jpg\" \/>\n<meta name=\"author\" content=\"Tornos Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tornos Abogados\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\"},\"author\":{\"name\":\"Tornos Abogados\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\"},\"headline\":\"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a\",\"datePublished\":\"2023-03-17T10:46:53+00:00\",\"dateModified\":\"2023-03-17T10:53:17+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\"},\"wordCount\":177,\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\"},\"articleSection\":[\"Noticias y Cursos\"],\"inLanguage\":\"ca-ES\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\",\"name\":\"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#website\"},\"datePublished\":\"2023-03-17T10:46:53+00:00\",\"dateModified\":\"2023-03-17T10:53:17+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#breadcrumb\"},\"inLanguage\":\"ca-ES\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tornosabogados.com\/ca\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#website\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/\",\"name\":\"Tornos Abogados\",\"description\":\"Referentes en derecho administrativo\",\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tornosabogados.com\/ca\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"ca-ES\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#organization\",\"name\":\"Tornos Abogados\",\"url\":\"https:\/\/www.tornosabogados.com\/ca\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"contentUrl\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"width\":451,\"height\":194,\"caption\":\"Tornos Abogados\"},\"image\":{\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\",\"name\":\"Tornos Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca-ES\",\"@id\":\"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"caption\":\"Tornos Abogados\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/","og_locale":"ca_ES","og_type":"article","og_title":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos","og_description":"Antonio Sala Cantarell, Socio de Tornos Abogados y Tom\u00e1s Cano Campos, Consejero Acad\u00e9mico de Tornos Abogados realizar\u00e1n el curso &#8220;El incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos: \u00bfIus variandi o riesgo imprevisible? \u00daltimas novedades y cuestiones pr\u00e1cticas m\u00e1s relevantes&#8220;. Este curso tiene por objetivo analizar el alcance del riesgo de ventura [&hellip;]","og_url":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/","og_site_name":"Tornos","article_published_time":"2023-03-17T10:46:53+00:00","article_modified_time":"2023-03-17T10:53:17+00:00","og_image":[{"url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2023\/03\/Camara-contratistas.jpg"}],"author":"Tornos Abogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tornos Abogados","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#article","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/"},"author":{"name":"Tornos Abogados","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97"},"headline":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a","datePublished":"2023-03-17T10:46:53+00:00","dateModified":"2023-03-17T10:53:17+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/"},"wordCount":177,"publisher":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#organization"},"articleSection":["Noticias y Cursos"],"inLanguage":"ca-ES"},{"@type":"WebPage","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/","url":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/","name":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a - Tornos","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#website"},"datePublished":"2023-03-17T10:46:53+00:00","dateModified":"2023-03-17T10:53:17+00:00","breadcrumb":{"@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#breadcrumb"},"inLanguage":"ca-ES","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornosabogados.com\/ca\/tornos-abogados-realiza-el-curso-el-incremento-excepcional-de-los-costes-de-ejecucion-de-los-contratos-publicos-en-la-camara-de-contratistas-de-obras-de-cataluna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tornosabogados.com\/ca\/"},{"@type":"ListItem","position":2,"name":"Curso sobre el incremento excepcional de los costes de ejecuci\u00f3n de los contratos p\u00fablicos en la C\u00e1mara de Contratistas de obras de Catalu\u00f1a"}]},{"@type":"WebSite","@id":"https:\/\/www.tornosabogados.com\/ca\/#website","url":"https:\/\/www.tornosabogados.com\/ca\/","name":"Tornos Abogados","description":"Referentes en derecho administrativo","publisher":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornosabogados.com\/ca\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"ca-ES"},{"@type":"Organization","@id":"https:\/\/www.tornosabogados.com\/ca\/#organization","name":"Tornos Abogados","url":"https:\/\/www.tornosabogados.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","contentUrl":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","width":451,"height":194,"caption":"Tornos Abogados"},"image":{"@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97","name":"Tornos Abogados","image":{"@type":"ImageObject","inLanguage":"ca-ES","@id":"https:\/\/www.tornosabogados.com\/ca\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","caption":"Tornos Abogados"}}]}},"_links":{"self":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/12735"}],"collection":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/comments?post=12735"}],"version-history":[{"count":7,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/12735\/revisions"}],"predecessor-version":[{"id":12749,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/posts\/12735\/revisions\/12749"}],"wp:attachment":[{"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/media?parent=12735"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/categories?post=12735"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/tags?post=12735"},{"taxonomy":"boletin","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/boletin?post=12735"},{"taxonomy":"articulo-lcsp","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/ca\/wp-json\/wp\/v2\/articulo-lcsp?post=12735"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}