{"id":10383,"date":"2019-05-01T12:00:00","date_gmt":"2019-05-01T10:00:00","guid":{"rendered":"https:\/\/www.tornosabogados.com\/novedades-juridicas-de-abril-2019\/"},"modified":"2020-10-22T00:53:51","modified_gmt":"2020-10-21T22:53:51","slug":"novedades-juridicas-de-abril-2019","status":"publish","type":"post","link":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/","title":{"rendered":"Novedades Jur\u00eddicas de abril 2019"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":[],"categories":[6],"tags":[],"boletin":[],"articulo-lcsp":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v20.10 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Novedades Jur\u00eddicas de abril 2019 - Tornos<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Novedades Jur\u00eddicas de abril 2019 - Tornos\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\" \/>\n<meta property=\"og:site_name\" content=\"Tornos\" \/>\n<meta property=\"article:published_time\" content=\"2019-05-01T10:00:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-21T22:53:51+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\" \/>\n\t<meta property=\"og:image:width\" content=\"451\" \/>\n\t<meta property=\"og:image:height\" content=\"194\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"author\" content=\"Tornos Abogados\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Tornos Abogados\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\"},\"author\":{\"name\":\"Tornos Abogados\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\"},\"headline\":\"Novedades Jur\u00eddicas de abril 2019\",\"datePublished\":\"2019-05-01T10:00:00+00:00\",\"dateModified\":\"2020-10-21T22:53:51+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\"},\"wordCount\":5,\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#organization\"},\"articleSection\":[\"Novedades jur\u00eddicas\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\",\"url\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\",\"name\":\"Novedades Jur\u00eddicas de abril 2019 - Tornos\",\"isPartOf\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#website\"},\"datePublished\":\"2019-05-01T10:00:00+00:00\",\"dateModified\":\"2020-10-21T22:53:51+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.tornosabogados.com\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Novedades Jur\u00eddicas de abril 2019\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#website\",\"url\":\"https:\/\/www.tornosabogados.com\/en\/\",\"name\":\"Tornos Abogados\",\"description\":\"Referentes en derecho administrativo\",\"publisher\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.tornosabogados.com\/en\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#organization\",\"name\":\"Tornos Abogados\",\"url\":\"https:\/\/www.tornosabogados.com\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"contentUrl\":\"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png\",\"width\":451,\"height\":194,\"caption\":\"Tornos Abogados\"},\"image\":{\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#\/schema\/logo\/image\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97\",\"name\":\"Tornos Abogados\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g\",\"caption\":\"Tornos Abogados\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Novedades Jur\u00eddicas de abril 2019 - Tornos","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/","og_locale":"en_US","og_type":"article","og_title":"Novedades Jur\u00eddicas de abril 2019 - Tornos","og_url":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/","og_site_name":"Tornos","article_published_time":"2019-05-01T10:00:00+00:00","article_modified_time":"2020-10-21T22:53:51+00:00","og_image":[{"width":451,"height":194,"url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","type":"image\/png"}],"author":"Tornos Abogados","twitter_card":"summary_large_image","twitter_misc":{"Written by":"Tornos Abogados"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#article","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/"},"author":{"name":"Tornos Abogados","@id":"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97"},"headline":"Novedades Jur\u00eddicas de abril 2019","datePublished":"2019-05-01T10:00:00+00:00","dateModified":"2020-10-21T22:53:51+00:00","mainEntityOfPage":{"@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/"},"wordCount":5,"publisher":{"@id":"https:\/\/www.tornosabogados.com\/en\/#organization"},"articleSection":["Novedades jur\u00eddicas"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/","url":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/","name":"Novedades Jur\u00eddicas de abril 2019 - Tornos","isPartOf":{"@id":"https:\/\/www.tornosabogados.com\/en\/#website"},"datePublished":"2019-05-01T10:00:00+00:00","dateModified":"2020-10-21T22:53:51+00:00","breadcrumb":{"@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.tornosabogados.com\/en\/novedades-juridicas-de-abril-2019\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.tornosabogados.com\/en\/"},{"@type":"ListItem","position":2,"name":"Novedades Jur\u00eddicas de abril 2019"}]},{"@type":"WebSite","@id":"https:\/\/www.tornosabogados.com\/en\/#website","url":"https:\/\/www.tornosabogados.com\/en\/","name":"Tornos Abogados","description":"Referentes en derecho administrativo","publisher":{"@id":"https:\/\/www.tornosabogados.com\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.tornosabogados.com\/en\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.tornosabogados.com\/en\/#organization","name":"Tornos Abogados","url":"https:\/\/www.tornosabogados.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornosabogados.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","contentUrl":"https:\/\/www.tornosabogados.com\/wp-content\/uploads\/2020\/11\/tornos-1.png","width":451,"height":194,"caption":"Tornos Abogados"},"image":{"@id":"https:\/\/www.tornosabogados.com\/en\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/318ca497d8c39816b99d827eb4492a97","name":"Tornos Abogados","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.tornosabogados.com\/en\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/806fee0fecf2bb1ca47e28be74aeac68?s=96&d=mm&r=g","caption":"Tornos Abogados"}}]}},"_links":{"self":[{"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/posts\/10383"}],"collection":[{"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/comments?post=10383"}],"version-history":[{"count":1,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/posts\/10383\/revisions"}],"predecessor-version":[{"id":10486,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/posts\/10383\/revisions\/10486"}],"wp:attachment":[{"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/media?parent=10383"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/categories?post=10383"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/tags?post=10383"},{"taxonomy":"boletin","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/boletin?post=10383"},{"taxonomy":"articulo-lcsp","embeddable":true,"href":"https:\/\/www.tornosabogados.com\/en\/wp-json\/wp\/v2\/articulo-lcsp?post=10383"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}